{"id":22391,"date":"2023-10-30T11:35:32","date_gmt":"2023-10-30T11:35:32","guid":{"rendered":"https:\/\/plazatorosalicante.com\/billets-de-corrida\/jose-ma-manzanares\/"},"modified":"2025-09-15T10:11:46","modified_gmt":"2025-09-15T10:11:46","slug":"jose-ma-manzanares","status":"publish","type":"page","link":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/","title":{"rendered":"Jos\u00e9 M\u00aa Manzanares"},"content":{"rendered":"<section class=\"l-section wpb_row height_large color_primary with_img parallax_ver\"><div class=\"l-section-img\" role=\"img\" aria-label=\"bullfighter morante de la puebla\" data-img-width=\"1273\" data-img-height=\"581\" style=\"background-image: url(https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/entradas-toros.jpg);\"><\/div><div class=\"l-section-overlay\" style=\"background:rgba(0,0,0,0.65)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=\u00a0\u00bbJos\u00e9 M\u00aa Manzanares Alicante billets de corrida\u00a0\u00bb font_container=\u00a0\u00bbtag:h1|text_align:left\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb]<div class=\"w-separator size_small\"><\/div><div class=\"w-hwrapper valign_top align_none\"><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/\"><span class=\"w-btn-label\">Acheter des billets<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto color_alternate type_sticky\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><nav class=\"w-menu us_custom_0147183a layout_hor style_blocks us_menu_1\" style=\"--main-ver-indent:0.5em;--main-hor-indent:1em;--main-color:inherit;--main-hover-color:var(--color-content-link);--main-active-bg-color:var(--color-content-primary);--main-active-color:#ffffff;\"><ul id=\"menu-entradas-menu\" class=\"menu\"><li id=\"menu-item-3654\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3654\"><a href=\"#espectaculo\">Espect\u00e1culo<\/a><\/li><li id=\"menu-item-3655\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3655\"><a href=\"#localidades\">Localidades<\/a><\/li><li id=\"menu-item-3653\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3653\"><a href=\"#information\">Informaci\u00f3n<\/a><\/li><li id=\"menu-item-3656\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3656\"><a href=\"#more\">Otros toreros<\/a><\/li><\/ul><style>@media ( max-width:600px ){.us_menu_1 .menu{display:block!important}.us_menu_1 .menu>li:not(:last-child){margin:0 0 var(--main-gap,0px)!important}}<\/style><\/nav><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"g-cols wpb_row via_grid cols_custom laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Le spectacle<\/h2>\n<p><strong>Quand Jos\u00e9 Mar\u00eda Manzanares combattra-t-il dans les ar\u00e8nes d&rsquo;Alicante ?<\/strong><\/p>\n<p>Le torero Jos\u00e9 Mar\u00eda Manzanares participera \u00e0 la Feria de Hogueras d&rsquo;Alicante le <strong>22 juin<\/strong> avec Roca Rey.<\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"g-cols wpb_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\" id=\"information\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Informations sur Manzanares<\/h2>\n<p>Jos\u00e9 Mar\u00eda Manzanares, connu dans le monde de la tauromachie sous le nom de \u00ab\u00a0Manzanares\u00a0\u00bb,<strong> est l&rsquo;une des figures les plus remarquables et les plus charismatiques de la tauromachie contemporaine<\/strong>. Son habilet\u00e9 et son style \u00e9l\u00e9gant lui ont valu une place de choix dans le monde de la tauromachie et ont fait de ses corridas des spectacles artistiques authentiques qui attirent des fans et des admirateurs du monde entier. Dans la ville d&rsquo;Alicante, Manzanares a laiss\u00e9 une marque profonde avec ses performances m\u00e9morables.  <\/p>\n<p>Alicante, avec ses ar\u00e8nes impressionnantes et sa longue tradition taurine, a \u00e9t\u00e9 le t\u00e9moin de certains des exploits les plus remarquables de Manzanares tout au long de sa carri\u00e8re. <b>Les plus chanceux <\/b>qui ont pu acheter des billets pour la corrida des Hogueras ont pu assister \u00e0 l&rsquo;une de ses meilleures corridas. \u00c0 cette occasion, Manzanares a affront\u00e9 un taureau f\u00e9roce avec une ma\u00eetrise in\u00e9gal\u00e9e. Sa tauromachie, caract\u00e9ris\u00e9e par sa s\u00e9r\u00e9nit\u00e9 et sa domination, est devenue un exemple d&rsquo;\u00e9l\u00e9gance et de technique dans l&rsquo;ar\u00e8ne.  <\/p>\n<p>Si vous \u00eates int\u00e9ress\u00e9, vous pouvez<strong>acheter vos billets pour la corrida de Manzanares \u00e0 Alicante \u00e0 <\/strong>travers ce site web.<\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-image align_left\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"800\" height=\"992\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg\" class=\"attachment-large size-large\" alt=\"torero jose maria manzanares\" loading=\"lazy\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg 800w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares-600x744.jpg 600w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares-242x300.jpg 242w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\" id=\"localidades\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Types de lieux<\/h2>\n<p>Dans les ar\u00e8nes d&rsquo;Alicante, vous pouvez trouver diff\u00e9rents types de si\u00e8ges, qui offrent diff\u00e9rentes perspectives et niveaux de confort aux spectateurs. Certains des si\u00e8ges disponibles \u00e0 Alicante sont les suivants : <\/p>\n<ol>\n<li><strong>Barri\u00e8re :<\/strong> Ce sont les si\u00e8ges les plus proches des ar\u00e8nes, situ\u00e9s \u00e0 l&rsquo;avant. Ils vous permettront de voir Manzanares avec une visibilit\u00e9 privil\u00e9gi\u00e9e.<\/li>\n<li><strong>Tendido:<\/strong> Ce sont les si\u00e8ges suivants les plus proches de l&rsquo;ar\u00e8ne, ils ont une bonne vue mais avec une l\u00e9g\u00e8re distance suppl\u00e9mentaire.<\/li>\n<li><strong>Bo\u00eetes :<\/strong> Il s&rsquo;agit d&rsquo;espaces priv\u00e9s et ferm\u00e9s situ\u00e9s aux \u00e9tages sup\u00e9rieurs des ar\u00e8nes. Ils vous permettent d&rsquo;assister au combat magistral de Manzanares dans le confort de votre espace priv\u00e9.<\/li>\n<li><strong>Andanada ou tribune :<\/strong> il s&rsquo;agit des zones les plus \u00e9lev\u00e9es de la place, avec des si\u00e8ges en gradins. Bien que la vue soit plus \u00e9loign\u00e9e, ils offrent une perspective d&rsquo;ensemble de la corrida. <\/li>\n<\/ol>\n<p>Enfin, les spectateurs pourront acheter leurs billets pour la corrida de Manzanares en fonction de la zone o\u00f9 ils sont assis.<\/p>\n<ul>\n<li><strong>Soleil:<\/strong> Ce sont g\u00e9n\u00e9ralement les billets les moins chers car ils sont situ\u00e9s dans la zone o\u00f9 le soleil est le plus.<\/li>\n<li><strong>Soleil et ombre:<\/strong> Ces si\u00e8ges alternent les zones o\u00f9 il fait soleil et d&rsquo;autres o\u00f9 il y a de l&rsquo;ombre.<\/li>\n<li><strong>Shadow:<\/strong> Ce sont les plus chers mais aussi les meilleurs puisqu&rsquo;ils permettent de mieux voir la corrida et avec plus de confort.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Comment s&rsquo;y rendre<\/h2>\n<p>Si vous \u00eates int\u00e9ress\u00e9 par la corrida qui aura lieu prochainement dans la ville d&rsquo;Alicante, nous vous laissons ci-dessous une carte pour localiser les ar\u00e8nes et les meilleurs itin\u00e9raires pour assister \u00e0 l&rsquo;\u00e9v\u00e9nement taurin.<\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><div class=\"w-html\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d35399.042686056564!2d-0.5275195917496097!3d38.35215535590105!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd6237acded1440b:0x3403579a002fcbc9!2sPlaza de Toros Alicante!5e0!3m2!1ses!2ses!4v1716982980993!5m2!1ses!2ses\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/div><\/div><\/div><div class=\"wpb_column vc_column_container type_sticky\"><div class=\"vc_column-inner\"><div class=\"w-separator size_large\"><\/div><div class=\"w-vwrapper us_custom_a9a6cc94 has_text_color align_center valign_top\" style=\"--vwrapper-gap:1.5rem\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h4>Achetez vos billets<\/h4>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/\"><span class=\"w-btn-label\">Acheter des billets<\/span><\/a><\/div><\/div><div class=\"w-separator size_large\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_c70c97eb height_medium\" id=\"more\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">Autres toreros d&rsquo;Alicante<\/h2>\n<p style=\"text-align: center;\">D\u00e9couvrez d&rsquo;autres toreros qui vont bient\u00f4t combattre dans la ville d&rsquo;Alicante.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-grid us_grid type_grid layout_2811 cols_3 preload_style_spinner ratio_1x1\" id=\"us_grid_1\" style=\"--columns:3;--gap:0.5rem;--item-ratio:1;\"><style>@media (max-width:1024px){#us_grid_1{--columns:2!important}}@media (max-width:600px){#us_grid_1{--columns:1!important}}.layout_2811 .w-grid-item-h{background:#25282b;border-radius:0rem}.layout_2811 .usg_post_image_1{transition-duration:0.3s;transform-origin:50% 100%;transform:scale(1) translate(0%,0%)}.layout_2811 .w-grid-item-h:focus-within .usg_post_image_1,.layout_2811 .w-grid-item-h:hover .usg_post_image_1{transform:scale(1.1) translate(0%,0%);opacity:1}.layout_2811 .usg_post_image_1{position:absolute!important;top:0!important;right:0!important;bottom:0!important;left:0!important}.layout_2811 .usg_post_title_1{color:#ffffff!important;font-size:1.6rem!important;position:absolute!important;left:0!important;bottom:0!important;right:0!important;background:linear-gradient(0deg,rgba(0,0,0,0.75),rgba(0,0,0,0))!important;padding:5rem 1.5rem 1.5rem 1.5rem!important}<\/style><div class=\"w-grid-list\">\t<article class=\"w-grid-item size_1x1 post-4069 page type-page status-publish has-post-thumbnail hentry\" data-id=\"4069\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/andy-carthagene\/\" class=\"w-grid-item-anchor\" aria-label=\"Andy Carthag\u00e8ne\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"608\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Andy-Cartagena.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Rejoneador andy carthag\u00e8ne\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Andy-Cartagena.jpg 741w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Andy-Cartagena-600x492.jpg 600w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Andy-Cartagena-300x246.jpg 300w\" sizes=\"auto, (max-width: 741px) 100vw, 741px\" \/><\/div><h3 class=\"w-post-elm post_title usg_post_title_1 has_text_color align_center entry-title color_link_inherit\">Andy Carthag\u00e8ne<\/h3>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-22404 page type-page status-publish has-post-thumbnail hentry\" data-id=\"22404\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/tomas-rufo\/\" class=\"w-grid-item-anchor\" aria-label=\"Tom\u00e1s Rufo\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/torero-tomas-rufo.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"tomas rufo torero\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/torero-tomas-rufo.jpg 800w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/torero-tomas-rufo-600x338.jpg 600w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/torero-tomas-rufo-300x169.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><h3 class=\"w-post-elm post_title usg_post_title_1 has_text_color align_center entry-title color_link_inherit\">Tom\u00e1s Rufo<\/h3>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-22420 page type-page status-publish has-post-thumbnail hentry\" data-id=\"22420\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/diego-ventura\/\" class=\"w-grid-item-anchor\" aria-label=\"Diego Ventura\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"537\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/diego-ventura-rejoneador.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"rejoneador diego ventura\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/diego-ventura-rejoneador.jpg 800w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/diego-ventura-rejoneador-600x403.jpg 600w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/diego-ventura-rejoneador-300x201.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><h3 class=\"w-post-elm post_title usg_post_title_1 has_text_color align_center entry-title color_link_inherit\">Diego Ventura<\/h3>\t\t<\/div>\r\n\t\t\t<\/article>\r\n<\/div>\t<div class=\"w-grid-preloader\">\r\n\t\t<div class=\"g-preloader type_1\">\r\n\t\t\t<div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:2,&quot;pagination&quot;:&quot;none&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;3&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;2811&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22type%22%3A%22post%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;ignore_sticky_posts&quot;:1,&quot;post_type&quot;:&quot;any&quot;,&quot;post__in&quot;:[&quot;3994&quot;,&quot;3990&quot;,&quot;3988&quot;,&quot;3978&quot;,&quot;3985&quot;],&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;product_visibility&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:[&quot;exclude-from-catalog&quot;],&quot;operator&quot;:&quot;NOT IN&quot;}],&quot;posts_per_page&quot;:&quot;3&quot;},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:&quot;RAND(1542661125)&quot;},&quot;type&quot;:&quot;grid&quot;,&quot;us_grid_post_type&quot;:&quot;ids&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:1,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;fr&quot;}}'><\/div>\r\n\t<\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_1\" title=\"tauromachie d&#039;alicante\" href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/\"><span class=\"w-btn-label\">Tous les \u00e9v\u00e8nements<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"Billets de corrida Rejones corrida Diego Ventura\" font_container=\"tag:h1|text_align:left\" use_theme_fonts=\"yes\"]Acheter des billetsEspect\u00e1culoLocalidadesInformaci\u00f3nOtros torerosLe spectacle Quand Diego Ventura combattra-t-il dans les ar\u00e8nes d&rsquo;Alicante ? Le rejoneador Diego Ventura participera \u00e0 la Foire des Hogueras \u00e0 Alicante le 16 juin avec deux autres rejoneadores : Andy Cartagena et Guillermo Hermoso. Informations sur Diego Ventura Dans le monde...","protected":false},"author":1,"featured_media":3674,"parent":4085,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22391","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante<\/title>\n<meta name=\"description\" content=\"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d&#039;Alicante [Disponible] [Disponible].\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante\" \/>\n<meta property=\"og:description\" content=\"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d&#039;Alicante [Disponible] [Disponible].\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/\" \/>\n<meta property=\"og:site_name\" content=\"Plaza de Toros de Alicante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laplazaalicantetour\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T10:11:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/\",\"name\":\"\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Jose_Maria_Manzanares.jpg\",\"datePublished\":\"2023-10-30T11:35:32+00:00\",\"dateModified\":\"2025-09-15T10:11:46+00:00\",\"description\":\"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d'Alicante [Disponible] [Disponible].\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Jose_Maria_Manzanares.jpg\",\"contentUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Jose_Maria_Manzanares.jpg\",\"width\":800,\"height\":992,\"caption\":\"torero jose maria manzanares\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/jose-ma-manzanares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Billets de corrida\",\"item\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/billets-de-corrida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jos\u00e9 M\u00aa Manzanares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/\",\"name\":\"Plaza de Toros de Alicante\",\"description\":\"Plaza de toros Alicante - Visitas Tur\u00edsticas y Culturales en Vivo para Individuales y Grupos\",\"publisher\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#organization\"},\"alternateName\":\"La Plaza Alicante Tour\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#organization\",\"name\":\"Plaza de toros Alicante\",\"alternateName\":\"La Plaza Alicante Tour\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Logo-plaza-toros-alicante.jpg\",\"contentUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Logo-plaza-toros-alicante.jpg\",\"width\":100,\"height\":100,\"caption\":\"Plaza de toros Alicante\"},\"image\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laplazaalicantetour\\\/\",\"https:\\\/\\\/www.instagram.com\\\/laplazaalicantetour\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante","description":"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d'Alicante [Disponible] [Disponible].","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/","og_locale":"fr_FR","og_type":"article","og_title":"\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante","og_description":"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d'Alicante [Disponible] [Disponible].","og_url":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/","og_site_name":"Plaza de Toros de Alicante","article_publisher":"https:\/\/www.facebook.com\/laplazaalicantetour\/","article_modified_time":"2025-09-15T10:11:46+00:00","og_image":[{"width":800,"height":992,"url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/","url":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/","name":"\u25b7 Jos\u00e9 Mar\u00eda Manzanares Billets de corrida : corrida Alicante","isPartOf":{"@id":"https:\/\/plazatorosalicante.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/#primaryimage"},"image":{"@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/#primaryimage"},"thumbnailUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg","datePublished":"2023-10-30T11:35:32+00:00","dateModified":"2025-09-15T10:11:46+00:00","description":"Vente de billets pour la corrida de Jos\u00e9 Mar\u00eda Manzanares \u00e0 Alicante. Site des ar\u00e8nes d'Alicante [Disponible] [Disponible].","breadcrumb":{"@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/#primaryimage","url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg","contentUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Jose_Maria_Manzanares.jpg","width":800,"height":992,"caption":"torero jose maria manzanares"},{"@type":"BreadcrumbList","@id":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/jose-ma-manzanares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/plazatorosalicante.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Billets de corrida","item":"https:\/\/plazatorosalicante.com\/fr\/billets-de-corrida\/"},{"@type":"ListItem","position":3,"name":"Jos\u00e9 M\u00aa Manzanares"}]},{"@type":"WebSite","@id":"https:\/\/plazatorosalicante.com\/fr\/#website","url":"https:\/\/plazatorosalicante.com\/fr\/","name":"Plaza de Toros de Alicante","description":"Plaza de toros Alicante - Visitas Tur\u00edsticas y Culturales en Vivo para Individuales y Grupos","publisher":{"@id":"https:\/\/plazatorosalicante.com\/fr\/#organization"},"alternateName":"La Plaza Alicante Tour","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plazatorosalicante.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/plazatorosalicante.com\/fr\/#organization","name":"Plaza de toros Alicante","alternateName":"La Plaza Alicante Tour","url":"https:\/\/plazatorosalicante.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/plazatorosalicante.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Logo-plaza-toros-alicante.jpg","contentUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Logo-plaza-toros-alicante.jpg","width":100,"height":100,"caption":"Plaza de toros Alicante"},"image":{"@id":"https:\/\/plazatorosalicante.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laplazaalicantetour\/","https:\/\/www.instagram.com\/laplazaalicantetour\/"]}]}},"_links":{"self":[{"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/pages\/22391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/comments?post=22391"}],"version-history":[{"count":3,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/pages\/22391\/revisions"}],"predecessor-version":[{"id":22395,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/pages\/22391\/revisions\/22395"}],"up":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/pages\/4085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/media\/3674"}],"wp:attachment":[{"href":"https:\/\/plazatorosalicante.com\/fr\/wp-json\/wp\/v2\/media?parent=22391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}