{"id":23215,"date":"2024-02-07T15:30:30","date_gmt":"2024-02-07T15:30:30","guid":{"rendered":"https:\/\/plazatorosalicante.com\/var-es-ter\/"},"modified":"2026-02-24T09:13:24","modified_gmt":"2026-02-24T09:13:24","slug":"var-es-ter","status":"publish","type":"page","link":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/","title":{"rendered":"V\u00e1r \u00e9s t\u00e9r"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_f9d0b101 height_auto color_primary with_img parallax_ver parallaxdir_reversed\"><div class=\"l-section-img\" role=\"img\" aria-label=\"K\u00e9p\" data-img-width=\"500\" data-img-height=\"461\" style=\"background-image: url(https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/tour-castillo-plaza-toros.webp);\"><\/div><div class=\"l-section-overlay\" style=\"background:linear-gradient(90deg,#1b122f,rgba(54,54,54,0.00))\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--columns-gap:0rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_medium\"><\/div><h1 class=\"w-text us_custom_51aa7753 us_animate_this\"><span class=\"w-text-h\"><span class=\"w-text-value\">Santa Barbara kast\u00e9ly \u00e9s bikaviadal-ar\u00e9na t\u00fara<\/span><\/span><\/h1><div class=\"w-separator size_small\"><\/div><div class=\"w-text us_custom_444d1fbc us_animate_this\"><span class=\"w-text-h\"><span class=\"w-text-value\">3 \u00f3r\u00e1s priv\u00e1t t\u00fara : 49\u20ac.<\/span><\/span><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_1\" target=\"_blank\" href=\"https:\/\/tickets.plazatorosalicante.com\/es\/1175-individual\/8162-visita-combinada-plaza-de-toros-castillo-de-santa-barbara\/info\"><span class=\"w-btn-label\">Jegyek v\u00e1s\u00e1rl\u00e1sa<\/span><\/a><\/div><div class=\"w-separator size_large\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">A jegy tartalmazza<\/h2>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"g-cols wpb_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image style_circle align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina.webp\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina.webp 700w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina-150x150.webp 150w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina-600x600.webp 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: left;\">1. L\u00e1togat\u00e1s a bikaviadal-ar\u00e9n\u00e1ban<\/h3>\n<p style=\"text-align: left;\">A vezetett t\u00far\u00e1t az alicantei bikaviadal-ar\u00e9na megtekint\u00e9s\u00e9vel kezdj\u00fck. Itt felfedezheti a bikaviadalok m\u0171v\u00e9szet\u00e9t, t\u00f6rt\u00e9net\u00e9t \u00e9s titkait. <\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image style_circle align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"510\" height=\"510\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/taxi-alicante.webp\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/taxi-alicante.webp 510w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/taxi-alicante-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/taxi-alicante-150x150.webp 150w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: left;\">Taxi k\u00f6zleked\u00e9s<\/h3>\n<p style=\"text-align: left;\">Miut\u00e1n megtekintette a teret, taxival elvissz\u00fck a Santa Barbara v\u00e1rhoz. Megsp\u00f3rolja a p\u00e9nzt \u00e9s a felvon\u00f3hoz val\u00f3 sorban \u00e1ll\u00e1st. A taxi sokkal k\u00e9nyelmesebb! <\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image style_circle align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp 700w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-150x150.webp 150w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-600x600.webp 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: left;\">3. L\u00e1togat\u00e1s a kast\u00e9lyban<\/h3>\n<p style=\"text-align: left;\">V\u00e1rosn\u00e9z\u00e9s\u00fcnket a v\u00e1ros egyik legszebb m\u0171eml\u00e9k\u00e9nek megtekint\u00e9s\u00e9vel z\u00e1rjuk. A kil\u00e1t\u00e1s \u00e9s a t\u00f6rt\u00e9nelem sz\u00f3hoz sem jut <\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_1\" target=\"_blank\" href=\"https:\/\/tickets.plazatorosalicante.com\/es\/1175-individual\/8162-visita-combinada-plaza-de-toros-castillo-de-santa-barbara\/info\"><span class=\"w-btn-label\">Jegyet v\u00e1s\u00e1rolni<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_f73c6c6b height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>\u00c1rak<\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\"><strong>1 f\u0151:<\/strong> 85\u20ac.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>2 f\u0151:<\/strong> 69\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>3 f\u0151:<\/strong> 59\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>4 &#8211; 5 f\u0151:<\/strong> 49\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>6 &#8211; 7 f\u0151:<\/strong> 39\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>8 &#8211; 11 f\u0151:<\/strong> 39\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>+12 f\u0151:<\/strong> 29\u20ac szem\u00e9lyenk\u00e9nt<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Gyermekek 14 \u00e9ves korig:<\/strong> 21\u20ac\/f\u0151*.  <\/span><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Menetrendek<\/h2>\n<ul>\n<li>H\u00e9tf\u0151t\u0151l szombatig 10 \u00f3r\u00e1t\u00f3l 15 \u00f3r\u00e1ig.<\/li>\n<li>A t\u00fara id\u0151tartama: k\u00f6r\u00fclbel\u00fcl 3 \u00f3ra.<\/li>\n<li>December 25-\u00e9n \u00e9s janu\u00e1r 1-j\u00e9n z\u00e1rva vagyunk.<\/li>\n<li>Nyitva december 31-\u00e9n, vas\u00e1rnap.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Nyelvek<\/h2>\n<ul>\n<li>Angol<\/li>\n<li>Angol<\/li>\n<li>Lengyel<\/li>\n<li>Olasz<\/li>\n<li>Orosz<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">Mindent l\u00e1tni fogsz<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-tabs layout_hor style_modern switch_hover has_scrolling\" style=\"--sections-title-size:1.3rem\"><div class=\"w-tabs-list items_2 align_center\" style=\"font-family:var(--h1-font-family);\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active\" aria-controls=\"content-rdbd\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Bullring<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-u789\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Santa Barbara kast\u00e9ly<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"rdbd\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-rdbd\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">Bullring<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-rdbd\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>&#8211; <strong> A t\u00fara tartalmazza:<\/strong> Priv\u00e1t idegenvezet\u0151<\/p>\n<p>&#8211; <strong> V\u00e1rosn\u00e9z\u0151 t\u00fara ideje:<\/strong> 1:30 h<\/p>\n<p><strong>&#8211; Mit fogsz l\u00e1tni?<\/strong><\/p>\n<ul>\n<li>Nagy ajt\u00f3<\/li>\n<li>Fektet\u00e9s 2<\/li>\n<li>Chapel<\/li>\n<li>\u00c1pol\u00e1s<\/li>\n<li>Patio de Cuadrillas \u00e9s Pase\u00edllo (Bull Run)<\/li>\n<li>Bikacsarnokok \u00e9s kar\u00e1mok<\/li>\n<li>Bullpen plat\u00f3<\/li>\n<li>Lovasudvar<\/li>\n<li>Panor\u00e1ma kil\u00e1t\u00e1s az Andanada 2-b\u0151l<\/li>\n<li>Eln\u00f6ks\u00e9g<\/li>\n<li>M\u00fazeum<\/li>\n<li>Ker\u00e9k<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-slider style_none fit_scaledown nav_none count_6\"><div class=\"w-slider-h\" aria-hidden=\"true\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"600\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina-600x600.webp\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"500\" data-rsh=\"461\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/tour-castillo-plaza-toros.webp\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"600\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/09\/capilla-600x600.jpg\"><span data-alt=\"capilla alicante toros\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"600\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/barrera-plaza-toros-600x600.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"600\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/capilla-plaza-toros-3-600x600.jpg\"><span data-alt=\"\"><\/span><\/a><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"600\" href=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Puerta-grande-plaza-alicante-600x600.jpg\"><span data-alt=\"az alicantei bikaviadal-ar\u00e9na f\u0151bej\u00e1rata\"><\/span><\/a><\/div><\/div><img decoding=\"async\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/plaza-de-toros-alicantina-600x600.webp\" width=\"600\" height=\"600\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:true,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;move&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:3000},&quot;autoScaleSliderWidth&quot;:600,&quot;autoScaleSliderHeight&quot;:600}'><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"u789\"><button class=\"w-tabs-section-header\" aria-controls=\"content-u789\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Santa Barbara kast\u00e9ly<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-u789\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>&#8211; <strong> Utaz\u00e1si id\u0151 a t\u00e9rr\u0151l a kast\u00e9lyhoz:<\/strong> 10 perc taxival, amelyet az \u00e1r tartalmaz.<\/p>\n<p>&#8211; <strong> A kast\u00e9lyl\u00e1togat\u00e1s ideje:<\/strong> 1:30 h<\/p>\n<p><strong>&#8211; Mit fogsz l\u00e1tni?<\/strong><\/p>\n<ul>\n<li>II. F\u00fcl\u00f6p terem<\/li>\n<li>Felvonul\u00e1si t\u00e9r<\/li>\n<li>V\u00e1rkoszor\u00fak \u00e9s harckorl\u00e1tok<\/li>\n<li>360 fokos kil\u00e1t\u00e1s<\/li>\n<\/ul>\n<p>Mag\u00e1nvezet\u0151nk elmes\u00e9li a v\u00e1rban t\u00f6rt\u00e9nt legfontosabb esem\u00e9nyeket, a v\u00e1r t\u00f6rt\u00e9net\u00e9t, \u00e9rdekess\u00e9geit \u00e9s a legfontosabb anekdot\u00e1kat. A v\u00e1r tetej\u00e9re is felvissz\u00fck \u00d6nt, hogy \u00e9lvezhesse a v\u00e1rosra ny\u00edl\u00f3 legszebb kil\u00e1t\u00e1st.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp 700w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-150x150.webp 150w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante-600x600.webp 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Egy\u00e9b t\u00far\u00e1k<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-grid us_grid type_grid layout_27 cols_3 preload_style_spinner ratio_1x1\" id=\"us_grid_1\" style=\"--columns:3;--gap:1.5rem;--item-ratio:1;\"><style>@media (max-width:1024px){#us_grid_1{--columns:2!important}}@media (max-width:600px){#us_grid_1{--columns:1!important}}.layout_27 .w-grid-item-h{background:var(--color-content-heading);border-radius:0.5rem;box-shadow:0 0rem 0rem rgba(0,0,0,0.1),0 0rem 0rem rgba(0,0,0,0.1);transition-duration:0.3s}.no-touch .layout_27 .w-grid-item-h:hover{box-shadow:0 0.2rem 0.4rem rgba(0,0,0,0.1),0 0.67rem 2rem rgba(0,0,0,0.15);z-index:4}.layout_27 .usg_post_image_1{transition-duration:0.3s;transform-origin:50% 50%;transform:scale(1) translate(0%,0%);opacity:0.5}.layout_27 .w-grid-item-h:focus-within .usg_post_image_1,.layout_27 .w-grid-item-h:hover .usg_post_image_1{transform:scale(1) translate(0%,0%);opacity:1}.layout_27 .usg_vwrapper_1{transition-duration:0.3s;transform-origin:50% 50%;transform:scale(1) translate(0%,0%)}.layout_27 .w-grid-item-h:focus-within .usg_vwrapper_1,.layout_27 .w-grid-item-h:hover .usg_vwrapper_1{transform:scale(1) translate(0%,0%);opacity:1;background:var(--color-content-bg)!important;color:var(--color-content-text)!important}.layout_27 .usg_post_image_1{position:absolute!important;left:0!important;top:0!important;bottom:0!important;right:0!important}.layout_27 .usg_vwrapper_1{color:var(--color-content-bg)!important;position:absolute!important;left:0!important;bottom:-1px!important;right:0!important;padding:1.5rem!important}.layout_27 .usg_post_title_1{color:inherit!important;font-weight:600!important;font-size:1.5rem!important}.layout_27 .usg_hwrapper_2{width:100%!important}<\/style><div class=\"w-grid-list\">\t<article class=\"w-grid-item size_1x1 post-23241 page type-page status-publish has-post-thumbnail hentry\" data-id=\"23241\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/piac-es-ter\/\" class=\"w-grid-item-anchor\" aria-label=\"Piac \u00e9s t\u00e9r\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/excursion-mercado-plaza-toros.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/excursion-mercado-plaza-toros.webp 500w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/excursion-mercado-plaza-toros-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/excursion-mercado-plaza-toros-150x150.webp 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><div class=\"w-vwrapper usg_vwrapper_1 has_text_color align_left valign_top\"><h2 class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\">Piac \u00e9s t\u00e9r<\/h2><div class=\"w-hwrapper usg_hwrapper_2 align_left valign_middle wrap\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_3 type_text start_date color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><div class=\"w-post-elm post_custom_field usg_post_custom_field_1 type_text precio color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><\/div><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-23366 page type-page status-publish has-post-thumbnail hentry\" data-id=\"23366\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/egyeni-latogatas\/\" class=\"w-grid-item-anchor\" aria-label=\"Egy\u00e9ni l\u00e1togat\u00e1s\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/12\/audioguia.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"l\u00e1togat\u00e1s a bikaviadal-ar\u00e9n\u00e1ba audio-guide-dal\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/12\/audioguia.webp 700w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/12\/audioguia-300x300.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/12\/audioguia-150x150.webp 150w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/12\/audioguia-600x600.webp 600w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div><div class=\"w-vwrapper usg_vwrapper_1 has_text_color align_left valign_top\"><h2 class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\">Egy\u00e9ni l\u00e1togat\u00e1s<\/h2><div class=\"w-hwrapper usg_hwrapper_2 align_left valign_middle wrap\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_3 type_text start_date color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><div class=\"w-post-elm post_custom_field usg_post_custom_field_1 type_text precio color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><\/div><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-23332 page type-page status-publish has-post-thumbnail hentry\" data-id=\"23332\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/vip-jegy\/\" class=\"w-grid-item-anchor\" aria-label=\"VIP jegy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" src=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/11\/Tour-plaza-de-toros-alicante-1024x652.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"l\u00e1togat\u00e1s az alicantei bikaviadal-ar\u00e9n\u00e1ban\" srcset=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/11\/Tour-plaza-de-toros-alicante-1024x652.webp 1024w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/11\/Tour-plaza-de-toros-alicante-600x382.webp 600w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/11\/Tour-plaza-de-toros-alicante-300x191.webp 300w, https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/11\/Tour-plaza-de-toros-alicante.webp 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"w-vwrapper usg_vwrapper_1 has_text_color align_left valign_top\"><h2 class=\"w-post-elm post_title usg_post_title_1 has_text_color entry-title color_link_inherit\">VIP jegy<\/h2><div class=\"w-hwrapper usg_hwrapper_2 align_left valign_middle wrap\"><div class=\"w-post-elm post_custom_field usg_post_custom_field_3 type_text start_date color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><div class=\"w-post-elm post_custom_field usg_post_custom_field_1 type_text precio color_link_inherit\"><span class=\"w-post-elm-value\"><\/span><\/div><\/div><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n<\/div>\t<div class=\"w-grid-preloader\">\r\n\t\t<div class=\"g-preloader type_1\">\r\n\t\t\t<div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;none&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;3&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;27&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22type%22%3A%22post%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;ignore_sticky_posts&quot;:1,&quot;post_type&quot;:&quot;any&quot;,&quot;post__in&quot;:[&quot;2424&quot;,&quot;7504&quot;,&quot;2446&quot;],&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;product_visibility&quot;,&quot;field&quot;:&quot;slug&quot;,&quot;terms&quot;:[&quot;exclude-from-catalog&quot;],&quot;operator&quot;:&quot;NOT IN&quot;}],&quot;posts_per_page&quot;:&quot;10&quot;},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;date&quot;:&quot;DESC&quot;}},&quot;type&quot;:&quot;grid&quot;,&quot;us_grid_post_type&quot;:&quot;ids&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:1,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;hu&quot;}}'><\/div>\r\n\t<\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><a title=\"alicantei bikaviadal-ar\u00e9na\" href=\"https:\/\/plazatorosalicante.com\/hu\/\">Bikaviadal-ar\u00e9na Alicante<\/a> &gt; <a title=\"l\u00e1togasson el az alicantei bikaviadal-ar\u00e9n\u00e1ba\" href=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/\">Bullring t\u00fara<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_bc30bd95 height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-actionbox us_custom_4c03b7cf has_text_color color_primary controls_right\"><div class=\"w-actionbox-text\"><h2 class=\"w-actionbox-title\">\u00d6n turisztikai szakember?<\/h2><div class=\"w-actionbox-description\"><p>Csatlakozzon turisztikai szakemberek h\u00e1l\u00f3zat\u00e1hoz, \u00e9s szerezzen fontos el\u0151ny\u00f6ket az alicantei bikaviadal-ar\u00e9n\u00e1ban szervezett t\u00far\u00e1k marketingje sor\u00e1n. Kattintson a gombra \u00e9s hagyja meg el\u00e9rhet\u0151s\u00e9g\u00e9t.<\/p>\n<\/div><\/div><div class=\"w-actionbox-controls\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/plazatorosalicante.com\/hu\/turisztikai-szakemberek\/\"><span class=\"w-btn-label\">Kapcsolat<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"VIP priv\u00e1t t\u00faraVIP priv\u00e1t t\u00fara Plaza + M\u00fazeum: 13\u20ac-t\u00f3l.Jegyek v\u00e1s\u00e1rl\u00e1saA jegy tartalmazza Priv\u00e1t idegenvezet\u0151 Egyik idegenvezet\u0151nk elmagyar\u00e1zza \u00d6nnek a bikaviadal-ar\u00e9na minden titk\u00e1t, \u00e9s v\u00e1laszol minden k\u00e9rd\u00e9s\u00e9re, valamint megtan\u00edtja, hogyan kell bikaviadalt v\u00edvni a k\u00f6pennyel. Felejthetetlen kultur\u00e1lis \u00e9lm\u00e9ny. K\u00fcl\u00f6nleges t\u00fara A program mag\u00e1ban foglalja a bikaviadal-m\u00fazeum megtekint\u00e9s\u00e9t, a kar\u00e1mokba val\u00f3 bejut\u00e1st, a m\u00e1sodik andanad\u00e1r\u00f3l \u00e9s az...","protected":false},"author":1,"featured_media":23216,"parent":23546,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-23215","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours<\/title>\n<meta name=\"description\" content=\"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours\" \/>\n<meta property=\"og:description\" content=\"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/\" \/>\n<meta property=\"og:site_name\" content=\"Plaza de Toros de Alicante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laplazaalicantetour\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T09:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 perc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/\",\"name\":\"\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/castillo-de-alicante.webp\",\"datePublished\":\"2024-02-07T15:30:30+00:00\",\"dateModified\":\"2026-02-24T09:13:24+00:00\",\"description\":\"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/castillo-de-alicante.webp\",\"contentUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/castillo-de-alicante.webp\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/var-es-ter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour plaza\",\"item\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/tour-plaza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"V\u00e1r \u00e9s t\u00e9r\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/\",\"name\":\"Plaza de Toros de Alicante\",\"description\":\"Plaza de toros Alicante - Visitas Tur\u00edsticas y Culturales en Vivo para Individuales y Grupos\",\"publisher\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#organization\"},\"alternateName\":\"La Plaza Alicante Tour\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#organization\",\"name\":\"Plaza de toros Alicante\",\"alternateName\":\"La Plaza Alicante t\u00fara\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Logo-plaza-toros-alicante.jpg\",\"contentUrl\":\"https:\\\/\\\/plazatorosalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Logo-plaza-toros-alicante.jpg\",\"width\":100,\"height\":100,\"caption\":\"Plaza de toros Alicante\"},\"image\":{\"@id\":\"https:\\\/\\\/plazatorosalicante.com\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laplazaalicantetour\\\/\",\"https:\\\/\\\/www.instagram.com\\\/laplazaalicantetour\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours","description":"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/","og_locale":"hu_HU","og_type":"article","og_title":"\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours","og_description":"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny","og_url":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/","og_site_name":"Plaza de Toros de Alicante","article_publisher":"https:\/\/www.facebook.com\/laplazaalicantetour\/","article_modified_time":"2026-02-24T09:13:24+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Becs\u00fclt olvas\u00e1si id\u0151":"5 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/","url":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/","name":"\u25b7 Santa B\u00e1rbara kast\u00e9ly + bikaviadal-ar\u00e9na t\u00fara | Alicante Tours","isPartOf":{"@id":"https:\/\/plazatorosalicante.com\/hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/#primaryimage"},"image":{"@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/#primaryimage"},"thumbnailUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp","datePublished":"2024-02-07T15:30:30+00:00","dateModified":"2026-02-24T09:13:24+00:00","description":"Priv\u00e1t idegenvezet\u00e9s: Fedezze fel Alicante k\u00e9t legfontosabb m\u0171eml\u00e9k\u00e9t. Taxi transzfer a kast\u00e9lyhoz - Pr\u00e9mium \u00e9lm\u00e9ny","breadcrumb":{"@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/#primaryimage","url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp","contentUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2024\/01\/castillo-de-alicante.webp","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/var-es-ter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/plazatorosalicante.com\/hu\/"},{"@type":"ListItem","position":2,"name":"Tour plaza","item":"https:\/\/plazatorosalicante.com\/hu\/tour-plaza\/"},{"@type":"ListItem","position":3,"name":"V\u00e1r \u00e9s t\u00e9r"}]},{"@type":"WebSite","@id":"https:\/\/plazatorosalicante.com\/hu\/#website","url":"https:\/\/plazatorosalicante.com\/hu\/","name":"Plaza de Toros de Alicante","description":"Plaza de toros Alicante - Visitas Tur\u00edsticas y Culturales en Vivo para Individuales y Grupos","publisher":{"@id":"https:\/\/plazatorosalicante.com\/hu\/#organization"},"alternateName":"La Plaza Alicante Tour","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plazatorosalicante.com\/hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/plazatorosalicante.com\/hu\/#organization","name":"Plaza de toros Alicante","alternateName":"La Plaza Alicante t\u00fara","url":"https:\/\/plazatorosalicante.com\/hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/plazatorosalicante.com\/hu\/#\/schema\/logo\/image\/","url":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Logo-plaza-toros-alicante.jpg","contentUrl":"https:\/\/plazatorosalicante.com\/wp-content\/uploads\/2023\/10\/Logo-plaza-toros-alicante.jpg","width":100,"height":100,"caption":"Plaza de toros Alicante"},"image":{"@id":"https:\/\/plazatorosalicante.com\/hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laplazaalicantetour\/","https:\/\/www.instagram.com\/laplazaalicantetour\/"]}]}},"_links":{"self":[{"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/pages\/23215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/comments?post=23215"}],"version-history":[{"count":9,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/pages\/23215\/revisions"}],"predecessor-version":[{"id":25379,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/pages\/23215\/revisions\/25379"}],"up":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/pages\/23546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/media\/23216"}],"wp:attachment":[{"href":"https:\/\/plazatorosalicante.com\/hu\/wp-json\/wp\/v2\/media?parent=23215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}